{"id":220,"date":"2021-02-13T10:52:39","date_gmt":"2021-02-13T10:52:39","guid":{"rendered":"http:\/\/115.243.153.202\/oscsc\/?page_id=220"},"modified":"2021-02-13T10:52:39","modified_gmt":"2021-02-13T10:52:39","slug":"districts","status":"publish","type":"page","link":"https:\/\/oscsc.in\/en\/information-desk\/districts\/","title":{"rendered":"Districts"},"content":{"rendered":"<p>Districts<\/p>","protected":false},"excerpt":{"rendered":"<p>Districts<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":217,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"ngg_post_thumbnail":0,"footnotes":"","_members_access_role":[],"_members_access_error":""},"class_list":["post-220","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/oscsc.in\/en\/wp-json\/wp\/v2\/pages\/220","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/oscsc.in\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/oscsc.in\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/oscsc.in\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/oscsc.in\/en\/wp-json\/wp\/v2\/comments?post=220"}],"version-history":[{"count":0,"href":"https:\/\/oscsc.in\/en\/wp-json\/wp\/v2\/pages\/220\/revisions"}],"up":[{"embeddable":true,"href":"https:\/\/oscsc.in\/en\/wp-json\/wp\/v2\/pages\/217"}],"wp:attachment":[{"href":"https:\/\/oscsc.in\/en\/wp-json\/wp\/v2\/media?parent=220"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}